{"id":24,"date":"2026-08-14T23:55:16","date_gmt":"2026-08-14T23:55:16","guid":{"rendered":"https:\/\/consultorahereandnow.cl\/jovenes\/?page_id=24"},"modified":"2026-08-15T00:46:38","modified_gmt":"2026-08-15T00:46:38","slug":"aspectos-legales-y-condiciones-generales-de-uso","status":"publish","type":"page","link":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/","title":{"rendered":"Aspectos Legales y Condiciones Generales de Uso"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"24\" class=\"elementor elementor-24\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0aaed8 e-flex e-con-boxed e-con e-parent\" data-id=\"a0aaed8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ab1a670 e-con-full e-flex e-con e-child\" data-id=\"ab1a670\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e1561e elementor-widget elementor-widget-text-editor\" data-id=\"2e1561e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Aspectos Legales y Condiciones Generales de Uso<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b86a20 e-flex e-con-boxed e-con e-parent\" data-id=\"0b86a20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-613c647 e-con-full e-flex e-con e-child\" data-id=\"613c647\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e3866d elementor-widget elementor-widget-text-editor\" data-id=\"8e3866d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>PRIMERO: GENERALIDADES<\/b><\/p><p>El presente documento, elaborado con fecha 18 de diciembre de 2020, regula los t\u00e9rminos y condiciones generales aplicables al acceso y uso que el Usuario realizar\u00e1 del Sitio Web consultorahereandnow.cl (en adelante \u201cConsultora Here &amp; Now\u201d o \u201cel Sitio Web\u201d indistintamente), as\u00ed como a cualquier tipo de informaci\u00f3n, contenido, imagen, video, audio u otro material comunicado o presente en el Sitio Web.<\/p><p>Para efectos del presente documento se entender\u00e1 como \u201cSitio Web\u201d: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de la navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, \u201cContenidos\u201d) y todos aquellos servicios o recuerdos en l\u00ednea que en su caso ofrezca a los usuarios (en adelante, \u201cServicios\u201d).<\/p><p>Consultora Here &amp; Now se reserva la facultad de modificar, en cualquier momento, y sin previo aviso, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento Consultora Here &amp; Now pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p><p>El acceso y uso del Sitio Web y del contenido relacionado o anexo, descrito en el presente documento, se regir\u00e1 \u00edntegramente por las leyes de la Rep\u00fablica de Chile. Por consiguiente, las visitas que el usuario realice en la plataforma que representa el sitio web, as\u00ed como los efectos jur\u00eddicos que \u00e9stas pudieran tener, quedan sometidos a las leyes y a la jurisdicci\u00f3n de los tribunales de justicia de la Rep\u00fablica de Chile. De particular importancia resultan la aplicaci\u00f3n de la Ley N\u00b0 19.628 de Protecci\u00f3n de Datos Personales y la Ley N\u00b0 19.496 sobre Derechos del Consumidor.<\/p><p>Adicionalmente, este sitio web y sus contenidos, est\u00e1n destinados \u00fanicamente a personas con residencia o domiciliadas en Chile.<\/p><p>Por lo mismo, Consultora Here &amp; Now no puede asegurar a personas que no cumplan con los requisitos previamente descritos, que el Sitio Web vaya a cumplir, total o parcialmente, con legislaciones extranjeras. As\u00ed, Consultora Here &amp; Now no se hace responsable en aquellos casos en que Usuarios extranjeros, sin residencia ni domicilio en Chile, tengan acceso o procedan a navegar en el Sitio Web.<\/p><p>Adicionalmente, Consultora Here &amp; Now adhiere en su totalidad al C\u00f3digo de Buenas Pr\u00e1cticas para el Comercio Electr\u00f3nico de la C\u00e1mara de Comercio de Santiago.<\/p><p>Se recomienda al usuario leer detenidamente el contenido de estos T\u00e9rminos y Condiciones Generales de Uso, as\u00ed como imprimir y conservar una copia de \u00e9stas en una unidad de disco local de almacenamiento, o de almacenamiento port\u00e1til, para su conveniencia y seguridad.<\/p><p><b>SEGUNDO.- INFORMACI\u00d3N DEL SITIO WEB Consultora Here &amp; Now<\/b><\/p><p>La titularidad de Consultora Here &amp; Now corresponde a XXXX RUT: XXXXX; debidamente representada por don XXXx, quien ostenta el siguiente cargo: Director Ejecutivo, C\u00e9dula Nacional de Identidad n\u00famero:XXXXX. Su personer\u00eda para actuar en representaci\u00f3n de Consultora Here &amp; Now consta en escritura p\u00fablica de fecha XX de XXX de XXXX, en el registro respectivo con el N.\u00ba XXXXX, la cual fue celebrada en la notar\u00eda p\u00fablica de Santiago de XXXXXXX.<\/p><p>Adicionalmente, para efectos de cualquier tipo de comunicaci\u00f3n, presentaci\u00f3n, consulta o reclamo relacionados con el uso o funcionamiento del Sitio Web, Consultora Here &amp; Now recibir\u00e1 todo tipo de comunicaciones al correo electr\u00f3nico: <a href=\"mailto:contacto@consultorahereandnow.cl\">contacto@consultorahereandnow.cl<\/a> <br \/>Consultora Here &amp; Now, se encuentra domiciliado(a) para estos efectos en XXXXX, of XX, comuna de XXXX.<\/p><p><b>TERCERO.- USUARIO<\/b><\/p><p>El acceso a este Sitio Web, la navegaci\u00f3n y uso del mismo, as\u00ed como cualquier espacio habilitado para interacciones entre Usuarios, o entre \u00e9ste y el Sitio Web (secciones de comentarios, espacios de blogging y micro blogging, y extensiones destinadas a esta funci\u00f3n), conferir\u00e1n a las personas la condici\u00f3n de \u201cUsuario\u201d. Por lo tanto, se entiende aceptar los T\u00e9rminos y Condiciones Presentes en este documento desde el momento de acceder al Sitio Web o a sus contenidos, as\u00ed como tambi\u00e9n todo tipo de futuras modificaciones que se hicieran a los T\u00e9rminos y Condiciones, sin perjuicio de lo que pudiera establecer futura legislaci\u00f3n dictada en la Rep\u00fablica de Chile destinada a regular esta clase de documentos, o que fuera aplicable al uso de Sitios Web.<\/p><p>Adicionalmente, el acceso al Sitio Web por parte del Usuario tendr\u00e1 un car\u00e1cter libre y gratuito, sin que \u00e9ste tenga que pagar por acceder al sitio o sus contenidos, m\u00e1s all\u00e1 del costo de la conexi\u00f3n a internet, en los casos que correspondiera.<\/p><p><b>Responsabilidad de los Usuarios<\/b><\/p><p>Consultora Here &amp; Now entrega al Usuario un servicio caracterizado por la diversidad del contenido proporcionado. El Usuario asume su responsabilidad al ingresar al Sitio Web, para realizar un correcto uso del mismo y sus contenidos. As\u00ed, esta responsabilidad se extender\u00e1, de forma no taxativa, a:<\/p><p>Usar la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por Consultora Here &amp; Now, sin que sea contrario a estos T\u00e9rminos y Condiciones, as\u00ed como al Ordenamiento Jur\u00eddico Chileno y a la Moral y el Orden P\u00fablico, o que de cualquier otra forma pudieran acarrear la vulneraci\u00f3n de derechos de terceros, o el funcionamiento y operaciones normales del Sitio Web.<\/p><p>Consultora Here &amp; Now se reserva el derecho de retirar todos aquellos comentarios e interacciones emanados de Usuarios que vulneren la ley, el respeto a la dignidad a la persona, que sean discriminatorios en base a raza, nacionalidad, sexo, orientaci\u00f3n sexual, estirpe o condici\u00f3n, as\u00ed como tambi\u00e9n aquellos que contengan contenido pornogr\u00e1fico o que constituyan mensajes conocidos como \u201cspam\u201d, o que atenten contra la juventud o infancia, el orden, o la seguridad p\u00fablica o que, a juicio de Consultora Here &amp; Now, no resulten apropiados para el Sitio Web.<\/p><p>De todas maneras, las opiniones manifestadas por los Usuarios, mediante comentarios u herramientas o extensiones de blogging o microblogging, son responsabilidad exclusiva de estos, y no refleja necesariamente la l\u00ednea editorial ni postura de Consultora Here &amp; Now.<\/p><p>El simple acceso a Consultora Here &amp; Now no supone una relaci\u00f3n comercial entre Consultora Here &amp; Now y el Usuario.<\/p><p><b>Capacidad Legal<\/b><\/p><p>El Sitio Web no requiere una edad m\u00ednima para poder acceder a su Contenido y Servicios; por lo tanto, estos T\u00e9rminos y Condiciones se aplicar\u00e1n indistintamente a todos los Usuarios del Sitio Web que cumplan con lo estipulado en este documento.<\/p><p>A\u00fan as\u00ed, las reglas legales de capacidad establecidas en el ordenamiento jur\u00eddico regir\u00e1n en todos aquellos casos donde su aplicaci\u00f3n sea pertinente. Por tanto, si una persona no tiene capacidad legal para contratar, debe abstenerse de utilizar los Contenidos y Servicios que requieran de esta capacidad. Consultora Here &amp; Now podr\u00e1, en cualquier momento, en forma temporal o definitiva, suspender la participaci\u00f3n de usuarios sobre los cuales se compruebe que carecen de capacidad legal para usar de los Servicios y Contenido que la requieran, o que proporcionen informaci\u00f3n falsa, inexacta o fraudulenta al Sitio Web.<\/p><p>El Sitio Web est\u00e1 dirigido principalmente a Usuarios residentes en la Rep\u00fablica de Chile. Consultora Here &amp; Now no asegura que el Sitio Web cumpla, parcial o totalmente, con legislaciones de otros pa\u00edses. Si el Usuario reside o est\u00e1 domiciliado en un pa\u00eds extranjero, y decide acceder y\/o navegar en este Sitio Web, lo har\u00e1 bajo su propia responsabilidad, asegur\u00e1ndose de que tal acceso y navegaci\u00f3n cumpla con lo dispuesto en la legislaci\u00f3n local que le sea aplicable, no asumiendo Consultora Here &amp; Now responsabilidad alguna que pueda derivar de dicho acceso.<\/p><p><b>CUARTO.- DERECHOS Y GARANT\u00cdAS DEL USUARIO DEL SITIO<\/b><\/p><p>El Usuario gozar\u00e1 de todos los derechos que le reconoce la legislaci\u00f3n sobre protecci\u00f3n al consumidor vigente en Chile, adicionalmente a los derechos que le otorgan estos T\u00e9rminos y Condiciones. Adem\u00e1s, el Usuario dispondr\u00e1 en todo momento de los derechos de informaci\u00f3n, rectificaci\u00f3n y cancelaci\u00f3n de los datos personales conforme a la Ley N\u00b0 19.628 sobre protecci\u00f3n de datos personales.<\/p><p><b>QUINTO.- RESPONSABILIDAD<\/b><\/p><p>Consultora Here &amp; Now no responder\u00e1, en ning\u00fan caso, por los siguientes hechos:<\/p><p>a.- Uso indebido que Usuarios o visitantes al Sitio Web realicen del contenido almacenado, as\u00ed como de los derechos de propiedad industrial o intelectual contenidos en el Sitio Web.<\/p><p>b.- Da\u00f1os y perjuicios, concretos o eventuales, causados a Usuarios derivados del funcionamiento de las herramientas de b\u00fasqueda del Sitio Web, as\u00ed como de errores generados por elementos t\u00e9cnicos del Sitio o del motor de b\u00fasqueda.<\/p><p>c.- Contenido de Sitios Web a las que los Usuarios puedan acceder con o sin autorizaci\u00f3n de Consultora Here &amp; Now.<\/p><p>d.- P\u00e9rdida, mal uso o uso no autorizado de contrase\u00f1a o c\u00f3digos de validaci\u00f3n, sea por parte del Usuario o de un tercero, de la forma expresada en estos T\u00e9rminos y Condiciones. De la misma forma, las partes reconocen y dejan constancia que el soporte computacional entregado por Consultora Here &amp; Now no es infalible, por lo tanto, pueden verificarse circunstancias ajenas a la voluntad de Consultora Here &amp; Now que puedan causar que el Sitio Web o su plataforma no se encuentren operativos durante un cierto per\u00edodo de tiempo.<\/p><p>e.- Informaci\u00f3n referida a Consultora Here &amp; Now que se encuentre en Sitios Web distintos o ajenos a Consultora Here &amp; Now.<br \/>En caso de estar ante alguno de estos supuestos, Consultora Here &amp; Now tomar\u00e1 todas las medidas para reestablecer el correcto funcionamiento del Sitio Web y de su sistema comunicacional lo m\u00e1s pronto posible, sin que pudiera imput\u00e1rsele alg\u00fan tipo de responsabilidad por aquello.<\/p><p>Consultora Here &amp; Now no asegura disponibilidad ni continuidad de funcionamiento del Sitio Web, y tampoco que en cualquier momento, los Usuarios puedan acceder a \u00e9l.<\/p><p>Consultora Here &amp; Now tampoco es responsable por la existencia de virus u otros elementos perjudiciales en los documentos o archivos almacenados en los sistemas inform\u00e1ticos de todo tipo de propiedad de los Usuarios.<\/p><p>Consultora Here &amp; Now no responder\u00e1 de perjuicios causados al Usuario, derivados del uso indebido de las tecnolog\u00edas y plataformas puestas a su disposici\u00f3n, cualquiera sea la forma en que se utilicen inadecuadamente estos elementos tecnol\u00f3gicos. Asimismo, Consultora Here &amp; Now no responder\u00e1 por da\u00f1os producidos por el uso indebido o mala fe de los Usuarios al utilizar el Sitio Web.<\/p><p>Al momento de registrarse, hacer login y para comunicarse, Consultora Here &amp; Now utiliza certificados digitales de seguridad (SSL), con el fin de encriptar la informaci\u00f3n. Consultora Here &amp; Now no almacena ni conserva datos financieros de sus Usuarios.<\/p><p><b>SEXTO.- POL\u00cdTICA DE SEGURIDAD DE DATOS<\/b><\/p><p>Consultora Here &amp; Now adoptar\u00e1 todas las medidas necesarias para resguardar los datos de sus Usuarios, como sistemas de encriptado de informaci\u00f3n, certificados de seguridad y otros semejantes o equivalentes que Consultora Here &amp; Now considere prudentes para estos efectos. En caso de realizarse cambios hechos por el Usuario en la informaci\u00f3n registrada o ingresada en el Sitio Web, o bien, si se produce la detecci\u00f3n de cualquier tipo de irregularidad atribuible al Usuario relacionada con la informaci\u00f3n entregada o simplemente como medida de protecci\u00f3n de identidad, el personal del Sitio Web se pondr\u00e1 en contacto con el Usuario, sea por v\u00eda telef\u00f3nica o por correo electr\u00f3nico, para corroborar los datos y la informaci\u00f3n, as\u00ed como para evitar la existencia de posibles fraudes.<\/p><p><b>Datos Personales<\/b><\/p><p>Al acceder al Sitio Web de Consultora Here &amp; Now los Usuarios o visitantes garantizan que la informaci\u00f3n que proporcionan para ingresar es veraz, completa, exacta y actualizada.<\/p><p>De acuerdo a lo establecido en la Ley N\u00b0 19.628 de Protecci\u00f3n de Datos Personales, los datos de este tipo que se suministren al Sitio Web, pasan a formar parte de una base de datos perteneciente a Consultora Here &amp; Now y ser\u00e1n destinados \u00fanica y exclusivamente para los fines que motivaron su entrega, especialmente para la comunicaci\u00f3n entre Consultora Here &amp; Now y sus Usuarios, y responder consultas. Estos datos nunca ser\u00e1n comunicados o compartidos con otras empresas sin expresa autorizaci\u00f3n de su titular (el Usuario) ni ser\u00e1n transferidos nacional o internacionalmente.<\/p><p><b>Consultora Here &amp; Now jam\u00e1s solicitar\u00e1 a sus Usuarios la entrega de datos personales o financieros a trav\u00e9s de correos electr\u00f3nicos.<\/b><\/p><p>Consultora Here &amp; Now presume que los datos incorporados por los Usuarios o por personas autorizadas por \u00e9stos son correctos y exactos.<\/p><p>Sin perjuicio de lo anterior, Consultora Here &amp; Now garantiza a todos sus Usuarios el libre ejercicio de los derechos contemplados en la Ley N\u00b0 19.628 de Protecci\u00f3n de Datos Personales en lo relativo a la informaci\u00f3n, modificaci\u00f3n, cancelaci\u00f3n y bloqueo de sus datos personales. En consecuencia, los Usuarios podr\u00e1n realizar requerimientos relacionados con los ya mencionados derechos, los que ser\u00e1n respondidos por Consultora Here &amp; Now en un plazo no superior a cinco d\u00edas corridos.<\/p><p><b>S\u00c9PTIMO.- PROPIEDAD INTELECTUAL Y DERECHOS RESERVADOS<\/b><\/p><p>Todos los derechos presentes en el Sitio Web, incluyendo la propiedad intelectual, respecto al mismo Sitio Web, p\u00e1ginas y otro tipo de contenido, como podr\u00eda ser, de forma no taxativa, textos de todo tipo, material gr\u00e1fico o audiovisual (incluyendo, pero no limitado a im\u00e1genes, clips de audio y videos), logos y logotipos, \u00edconos de todo tipo, material y contenido descargable, recopilaciones de datos e informaci\u00f3n y c\u00f3digos fuente de la p\u00e1gina, son de propiedad de Consultora Here &amp; Now.<\/p><p>Cualquier otra marca comercial que tuviera presencia en el Sitio Web y cuyos derechos no sean de propiedad de Consultora Here &amp; Now, pertenecer\u00e1 a sus debidos due\u00f1os.<\/p><p><b>OCTAVO.-\u00a0<span>PROPIEDAD INTELECTUAL<\/span><\/b><\/p><p>Queda totalmente prohibido cualquier tipo de utilizaci\u00f3n del contenido de Consultora Here &amp; Now, incluidas su reproducci\u00f3n, modificaci\u00f3n, distribuci\u00f3n, transmisi\u00f3n, posterior publicaci\u00f3n, exhibici\u00f3n o representaci\u00f3n total o parcial del mismo, sin el consentimiento expreso de su autor. No podr\u00e1 utilizarse el logotipo de Consultora Here &amp; Now sin autorizaci\u00f3n previa de Consultora Here &amp; Now. Adem\u00e1s, mediante la adquisici\u00f3n de un producto o servicio, Consultora Here &amp; Now no confiere ni cede al adquirente derecho alguno de alteraci\u00f3n, explotaci\u00f3n, reproducci\u00f3n, distribuci\u00f3n o comunicaci\u00f3n p\u00fablica sobre el mismo, reserv\u00e1ndose Consultora Here &amp; Now todos estos derechos. Para la cesi\u00f3n de los citados derechos precisar\u00e1 el previo consentimiento por escrito por parte de Consultora Here &amp; Now.<\/p><p><b>NOVENO.- PROPIEDAD INDUSTRIAL<\/b><\/p><p>Consultora Here &amp; Now es titular de los derechos de propiedad industrial referidos a sus productos y servicios, y espec\u00edficamente los relativos a la marca registrada Consultora Here &amp; Now y a sus contratos de derecho inform\u00e1tico.<\/p><p>Respecto a las citas de productos y servicios de terceros, Consultora Here &amp; Now reconoce a favor de sus titulares los correspondientes derechos de propiedad industrial e intelectual.<\/p><p><span>\u00a0<\/span><\/p><p><b>D\u00c9CIMO.- INFRACCIONES DE PROPIEDAD<\/b><\/p><p>La utilizaci\u00f3n no autorizada de la informaci\u00f3n contenida en Consultora Here &amp; Now, su reventa, as\u00ed como la lesi\u00f3n de los derechos de propiedad intelectual o industrial de Consultora Here &amp; Now dar\u00e1 lugar a las responsabilidades legalmente establecidas. El Usuario se har\u00e1 cargo de los gastos jur\u00eddicos procesales incurridos por Consultora Here &amp; Now y otros cargos asociados de conformidad a lo previsto en estos T\u00e9rminos y Condiciones.<\/p><p><span>\u00a0<\/span><\/p><p><span><b>D\u00c9CIMOPRIMERO.- POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS<\/b><\/span><\/p><p>A trav\u00e9s de algunos apartados de esta p\u00e1gina web podr\u00e1n serle requeridos datos de car\u00e1cter personal, por lo que le informamos que el tratamiento que se har\u00e1 de dichos datos cumplir\u00e1 en todo momento, con las obligaciones establecidas en la legislaci\u00f3n vigente de protecci\u00f3n de datos de car\u00e1cter personal. Cabe se\u00f1alar que Consultora Here &amp; Now no recoge datos personales autom\u00e1ticamente, los \u00fanicos datos personales que se recogen son aquellos que los Usuarios facilitan a trav\u00e9s de formularios de contacto.<\/p><p>M\u00e1s informaci\u00f3n respecto de la Pol\u00edtica de Privacidad de Consultora Here &amp; Now en <a href=\"https:\/\/consultorahereandnow.cl\/jovenes\/politicas-de-privacidad\/\">https:\/\/consultorahereandnow.cl\/jovenes\/politicas-de-privacidad\/<\/a><\/p><p><a href=\"http:\/\/www.derecho-chile.cl\/politica-de-privacidad-y-proteccion-de-datos\/\" target=\"_blank\" rel=\"noopener\">Ver aqu\u00ed la Pol\u00edtica de Privacidad y Protecci\u00f3n de Datos del sitio web Derecho Chile.<\/a><\/p><p>Los interesados podr\u00e1n ejercitar los derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n, mediante petici\u00f3n escrita dirigida a la siguiente direcci\u00f3n de correo electr\u00f3nico: <a href=\"mailto:contacto@consultorahereandnow.cl\">contacto@consultorahereandnow.cl<\/a><\/p><p><b>D\u00c9CIMOSEGUNDO.- CONFIDENCIALIDAD<\/b><\/p><p>Los productos y servicios suministrados al Usuario son para su uso exclusivo y \u00fanico, por lo que \u00e9l mismo est\u00e1 obligado a mantener total confidencialidad en relaci\u00f3n con los datos e informaci\u00f3n transmitidos. El Usuario no podr\u00e1 ceder dicha informaci\u00f3n o parte de la misma a terceros sin el consentimiento previo y por escrito de Consultora Here &amp; Now.<\/p><p><b>D\u00c9CIMOTERCERO.- MODIFICACI\u00d3N DE LOS T\u00c9RMINOS Y CONDICIONES<\/b><\/p><p>Consultora Here &amp; Now puede modi\ufb01car los T\u00e9rminos y Condiciones en cualquier momento conforme la legislaci\u00f3n vigente. Cualquier cambio en los T\u00e9rminos y Condiciones ser\u00e1 publicado en esta p\u00e1gina y, sin perjuicio de la comunicaci\u00f3n que se har\u00e1 a los Usuarios registrados, ser\u00e1n de aplicaci\u00f3n inmediata. Lo exhortamos a que visite nuestra plataforma con frecuencia para mantenerse informado acerca de c\u00f3mo utilizamos su informaci\u00f3n personal.<\/p><p><b>D\u00c9CIMOCUARTO.- JURISDICCI\u00d3N Y LEY APLICABLE<\/b><\/p><p>Todo lo relativo a la interpretaci\u00f3n y cumplimiento de los presentes T\u00e9rminos y Condiciones estar\u00e1 regido exclusivamente por las leyes de la Rep\u00fablica de Chile.<\/p><p>Consultora Here &amp; Now fija su domicilio en Santiago para efecto de someterse a la jurisdicci\u00f3n de sus Tribunales Ordinarios de Justicia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aspectos Legales y Condiciones Generales de Uso PRIMERO: GENERALIDADES El presente documento, elaborado con fecha 18 de diciembre de 2020, regula los t\u00e9rminos y condiciones generales aplicables al acceso y uso que el Usuario realizar\u00e1 del Sitio Web consultorahereandnow.cl (en adelante \u201cConsultora Here &amp; Now\u201d o \u201cel Sitio Web\u201d indistintamente), [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-24","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aspectos Legales y Condiciones Generales de Uso<\/title>\n<meta name=\"description\" content=\"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aspectos Legales y Condiciones Generales de Uso\" \/>\n<meta property=\"og:description\" content=\"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/\" \/>\n<meta property=\"og:site_name\" content=\"Here and Now\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-15T00:46:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consultorahereandnow.cl\/jovenes\/wp-content\/uploads\/2026\/08\/favicon-here-and-now.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Aspectos Legales y Condiciones Generales de Uso\" \/>\n<meta name=\"twitter:description\" content=\"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/consultorahereandnow.cl\/jovenes\/wp-content\/uploads\/2026\/08\/favicon-here-and-now.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/aspectos-legales-y-condiciones-generales-de-uso\\\/\",\"url\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/aspectos-legales-y-condiciones-generales-de-uso\\\/\",\"name\":\"Aspectos Legales y Condiciones Generales de Uso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/#website\"},\"datePublished\":\"2026-08-14T23:55:16+00:00\",\"dateModified\":\"2026-08-15T00:46:38+00:00\",\"description\":\"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/aspectos-legales-y-condiciones-generales-de-uso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/aspectos-legales-y-condiciones-generales-de-uso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/aspectos-legales-y-condiciones-generales-de-uso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aspectos Legales y Condiciones Generales de Uso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/#website\",\"url\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/\",\"name\":\"Here and Now\",\"description\":\"Desarrollamos habilidades en los j\u00f3venes para navegar la Vida.\",\"publisher\":{\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/#organization\",\"name\":\"Here and Now\",\"url\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/logotipo-here-and-now-2.png\",\"contentUrl\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/logotipo-here-and-now-2.png\",\"width\":454,\"height\":100,\"caption\":\"Here and Now\"},\"image\":{\"@id\":\"https:\\\/\\\/consultorahereandnow.cl\\\/jovenes\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aspectos Legales y Condiciones Generales de Uso","description":"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/","og_locale":"es_ES","og_type":"article","og_title":"Aspectos Legales y Condiciones Generales de Uso","og_description":"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.","og_url":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/","og_site_name":"Here and Now","article_modified_time":"2026-08-15T00:46:38+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-content\/uploads\/2026\/08\/favicon-here-and-now.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Aspectos Legales y Condiciones Generales de Uso","twitter_description":"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.","twitter_image":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-content\/uploads\/2026\/08\/favicon-here-and-now.jpg","twitter_misc":{"Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/","url":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/","name":"Aspectos Legales y Condiciones Generales de Uso","isPartOf":{"@id":"https:\/\/consultorahereandnow.cl\/jovenes\/#website"},"datePublished":"2026-08-14T23:55:16+00:00","dateModified":"2026-08-15T00:46:38+00:00","description":"La presente p\u00e1gina contiene informaci\u00f3n acerca de los Aspectos Legales, T\u00e9rminos y Condiciones de Uso bajo los que se rige este sitio web.","breadcrumb":{"@id":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/consultorahereandnow.cl\/jovenes\/aspectos-legales-y-condiciones-generales-de-uso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/consultorahereandnow.cl\/jovenes\/"},{"@type":"ListItem","position":2,"name":"Aspectos Legales y Condiciones Generales de Uso"}]},{"@type":"WebSite","@id":"https:\/\/consultorahereandnow.cl\/jovenes\/#website","url":"https:\/\/consultorahereandnow.cl\/jovenes\/","name":"Here and Now","description":"Desarrollamos habilidades en los j\u00f3venes para navegar la Vida.","publisher":{"@id":"https:\/\/consultorahereandnow.cl\/jovenes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consultorahereandnow.cl\/jovenes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/consultorahereandnow.cl\/jovenes\/#organization","name":"Here and Now","url":"https:\/\/consultorahereandnow.cl\/jovenes\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/consultorahereandnow.cl\/jovenes\/#\/schema\/logo\/image\/","url":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-content\/uploads\/2026\/08\/logotipo-here-and-now-2.png","contentUrl":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-content\/uploads\/2026\/08\/logotipo-here-and-now-2.png","width":454,"height":100,"caption":"Here and Now"},"image":{"@id":"https:\/\/consultorahereandnow.cl\/jovenes\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/pages\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":15,"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/pages\/24\/revisions"}],"predecessor-version":[{"id":1153,"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/pages\/24\/revisions\/1153"}],"wp:attachment":[{"href":"https:\/\/consultorahereandnow.cl\/jovenes\/wp-json\/wp\/v2\/media?parent=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}